{"id":2701,"date":"2026-03-02T10:38:30","date_gmt":"2026-03-02T09:38:30","guid":{"rendered":"https:\/\/eszter-maura.eu\/?page_id=2701"},"modified":"2026-03-04T10:34:28","modified_gmt":"2026-03-04T09:34:28","slug":"","status":"publish","type":"page","link":"https:\/\/eszter-maura.eu\/fr\/about\/","title":{"rendered":"\u00a0\u00c0 propos","raw":"\u00a0\u00c0 propos"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Je suis danseuse, \u00e9crivaine (et nomade \u00e0 temps partiel), et je suis l\u00e0 pour t&rsquo;aider \u00e0 te sentir pleinement toi-m\u00eame dans ton corps, \u00e0 y trouver du plaisir et \u00e0 oser prendre ta place, par la danse\u00a0; et pour d\u00e9mystifier la musicalit\u00e9 afin que tu puisse t&rsquo;appuyer sur ta musique comme un socle solide pour ta danse, \u00e9tablir un lien culturel en incarnant la musique, r\u00e9duire ton trac<\/h4>\n\n\n\n<p><strong>\u2013 et devenir une artiste confiante et expressive qui s\u2019approprie la sc\u00e8ne.<\/strong><\/p>\n\n\n\n<p>Je me d\u00e9finis comme danseuse orientale, mais depuis plus de 30 ans, j&rsquo;explore un large \u00e9ventail de styles de danse et de genres musicaux issus de diff\u00e9rentes traditions du monde entier, acqu\u00e9rant ainsi une compr\u00e9hension profonde et compl\u00e8te du rythme et du mouvement.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"618\" height=\"1024\" data-attachment-id=\"2714\" data-permalink=\"https:\/\/eszter-maura.eu\/fr\/homepage\/l1008108\/#main\/\" data-orig-file=\"https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2025\/07\/L1008108-scaled.jpg?fit=1544%2C2560&amp;ssl=1\" data-orig-size=\"1544,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;19&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;LEICA M10-P&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1596382419&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.0055555555555556&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Molenbeek &amp;#8211; Baaterflek\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2025\/07\/L1008108-scaled.jpg?fit=618%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2025\/07\/L1008108.jpg?resize=618%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-2714\" style=\"width:337px;height:auto\" srcset=\"https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2025\/07\/L1008108-scaled.jpg?resize=618%2C1024&amp;ssl=1 618w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2025\/07\/L1008108-scaled.jpg?resize=181%2C300&amp;ssl=1 181w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2025\/07\/L1008108-scaled.jpg?resize=768%2C1273&amp;ssl=1 768w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2025\/07\/L1008108-scaled.jpg?resize=926%2C1536&amp;ssl=1 926w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2025\/07\/L1008108-scaled.jpg?resize=1235%2C2048&amp;ssl=1 1235w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2025\/07\/L1008108-scaled.jpg?w=1544&amp;ssl=1 1544w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2025\/07\/L1008108-scaled.jpg?w=1440&amp;ssl=1 1440w\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" \/><\/figure>\n<\/div>\n\n\n<p>Outre mes 25 ans d&rsquo;exp\u00e9rience en Raqs Sharqi (danse orientale), qui est devenue ma langue maternelle en danse, je me suis form\u00e9e \u00e0 de nombreuses danses traditionnelles et sociales du monde entier, telles que la salsa, les danses afro-colombiennes, les danses d&rsquo;Afrique de l&rsquo;Ouest, les danses folkloriques hongroises et d&rsquo;Europe occidentale, les danses du sud de l&rsquo;Italie, l&rsquo;improvisation contact et le flamenco, entre autres.<\/p>\n\n\n\n<p>Je continue d&rsquo;apprendre et de m&rsquo;\u00e9merveiller devant la beaut\u00e9 et l&rsquo;interconnexion des diff\u00e9rentes traditions musicales et dansantes.<\/p>\n\n\n\n<p>Je poss\u00e8de \u00e9galement plus de dix ans de formation en musique classique occidentale et une connaissance approfondie des musiques traditionnelles de nombreuses r\u00e9gions, avec un int\u00e9r\u00eat particulier pour les musiques arabe et \u00e9gyptienne.<\/p>\n\n\n\n<p>Dans une vie ant\u00e9rieure, j&rsquo;\u00e9tais architecte\/ing\u00e9nieure et j&rsquo;ai acquis les comp\u00e9tences n\u00e9cessaires pour d\u00e9composer et expliquer en d\u00e9tail les concepts li\u00e9s \u00e0 la danse ou \u00e0 la musique aux danseuses d&rsquo;un esprit analytique.<\/p>\n\n\n\n<p>J&rsquo;ai aussi \u00e9t\u00e9 traductrice, ce qui, combin\u00e9 \u00e0 mon exp\u00e9rience dans divers styles de danse et de musique, m&rsquo;a permis de d\u00e9velopper une compr\u00e9hension des liens entre les cultures, particuli\u00e8rement pr\u00e9cieuse pour les danseuses qui ne sont pas issues des cultures fondatrices du Raqs Sharqi.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"480\" data-attachment-id=\"2370\" data-permalink=\"https:\/\/eszter-maura.eu\/fr\/contact\/f306b80c-a5d6-4126-9191-94a995f6bfdd\/#main\/\" data-orig-file=\"https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD-scaled.jpeg?fit=2560%2C1707&amp;ssl=1\" data-orig-size=\"2560,1707\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;C. Devos&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bota &amp;#8211; on the bike\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD-scaled.jpeg?fit=720%2C480&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD.jpeg?resize=720%2C480&#038;ssl=1\" alt=\"\" class=\"wp-image-2370\" style=\"width:451px;height:auto\" srcset=\"https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD-scaled.jpeg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD-scaled.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD-scaled.jpeg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD-scaled.jpeg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD-scaled.jpeg?resize=2048%2C1365&amp;ssl=1 2048w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD-scaled.jpeg?resize=272%2C182&amp;ssl=1 272w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD-scaled.jpeg?w=1440&amp;ssl=1 1440w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD-scaled.jpeg?w=2160&amp;ssl=1 2160w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n<\/div>\n\n\n<p>Ma soif d&rsquo;aventure m&rsquo;a men\u00e9e \u00e0 un p\u00e9riple de 8&nbsp;000&nbsp;km \u00e0 v\u00e9lo le long des c\u00f4tes d&rsquo;Europe occidentale et m\u00e9ridionale, de Bruxelles \u00e0 Cadix puis \u00e0 G\u00eanes, en vivant sous une tente pendant pr\u00e8s d&rsquo;un an. Ce voyage m&rsquo;a aussi appris \u00e0 tracer mon propre chemin, sans me soucier des attentes de la soci\u00e9t\u00e9 \u2013&nbsp;une femme grosse, d&rsquo;un certain \u00e2ge, avec des maladies chroniques&nbsp;\u2013, afin de t&rsquo;aider \u00e0 acqu\u00e9rir les connaissances, le pragmatisme et la confiance en toi n\u00e9cessaires pour t&rsquo;approprier ton corps et ton parcours cr\u00e9atif, quel que soit ton  niveau en danse.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"1024\" data-attachment-id=\"2823\" data-permalink=\"https:\/\/eszter-maura.eu\/fr\/about\/fbsize-3954\/#main\/\" data-orig-file=\"https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2026\/03\/fbsize-3954.jpg?fit=1367%2C2048&amp;ssl=1\" data-orig-size=\"1367,2048\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;7.1&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D750&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1525873129&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;135&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fbsize-3954\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2026\/03\/fbsize-3954.jpg?fit=684%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2026\/03\/fbsize-3954.jpg?resize=684%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-2823\" style=\"width:338px;height:auto\" srcset=\"https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2026\/03\/fbsize-3954.jpg?resize=684%2C1024&amp;ssl=1 684w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2026\/03\/fbsize-3954.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2026\/03\/fbsize-3954.jpg?resize=768%2C1151&amp;ssl=1 768w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2026\/03\/fbsize-3954.jpg?resize=1025%2C1536&amp;ssl=1 1025w, https:\/\/i0.wp.com\/eszter-maura.eu\/wp-content\/uploads\/2026\/03\/fbsize-3954.jpg?w=1367&amp;ssl=1 1367w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/><\/figure>\n<\/div>\n\n\n<p>Je crois que la danse est et devrait \u00eatre \u00ab&nbsp;la musique rendue visible&nbsp;\u00bb, et je m\u2019appuie sur la musique pour guider mes cr\u00e9ations. Je crois que la musicalit\u00e9 est primordiale pour tout danseur&nbsp;; et que c\u2019est une comp\u00e9tence qui peut s\u2019acqu\u00e9rir et se d\u00e9velopper \u00e0 tout \u00e2ge et \u00e0 tout niveau. Je crois qu\u2019il est possible de se connecter \u00e0 la musique et \u00e0 la danse \u00e9gyptiennes \u00e0 travers sa propre exp\u00e9rience culturelle, et de cr\u00e9er des danses inspir\u00e9es de sa propre vision artistique, dans le plus grand respect des cultures d\u2019origine.<\/p>\n\n\n\n<p>Je crois que la danse, port\u00e9e par la musique, permet d\u2019acc\u00e9der \u00e0 ses v\u00e9rit\u00e9s les plus profondes&nbsp;; que nous avons tous en nous la capacit\u00e9 d\u2019explorer ces profondeurs et de cr\u00e9er un art qui nous relie \u00e0 nous-m\u00eames et touche les autres.<\/p>\n\n\n\n<p>Je crois qu\u2019\u00e0 travers l\u2019art de la danse, on apprend \u00e0 s\u2019approprier son corps, \u00e0 s\u2019y sentir bien et \u00e0 y trouver de la joie&nbsp;; et qu\u2019en cr\u00e9ant un tel art, on devient un vecteur de beaut\u00e9, ind\u00e9pendamment de son apparence ou de son estime de soi.<\/p>\n\n\n\n<p>Je suis l\u00e0 pour t&rsquo;aider \u00e0 te r\u00e9approprier ton corps et \u00e0 t&rsquo;y sentir bien, \u00e0 y trouver du plaisir et \u00e0 oser prendre ta place, par la danse ; et pour t&rsquo;aider \u00e0 donner du sens \u00e0 toutes les facettes de tes connaissances en danse gr\u00e2ce \u00e0 une compr\u00e9hension et une connexion profondes avec la musique.<\/p>\n\n\n\n<p>\u2013 afin que tu puisse commencer \u00e0 cr\u00e9er des danses qui touchent l&rsquo;\u00e2me de ton public.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100 is-style-fill\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" style=\"background-color:#77041b\"><strong>Contacte-moi<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false,"raw":"<!-- wp:heading {\"level\":4} -->\n<h4 class=\"wp-block-heading\">Je suis danseuse, \u00e9crivaine (et nomade \u00e0 temps partiel), et je suis l\u00e0 pour t'aider \u00e0 te sentir pleinement toi-m\u00eame dans ton corps, \u00e0 y trouver du plaisir et \u00e0 oser prendre ta place, par la danse\u00a0; et pour d\u00e9mystifier la musicalit\u00e9 afin que tu puisse t'appuyer sur ta musique comme un socle solide pour ta danse, \u00e9tablir un lien culturel en incarnant la musique, r\u00e9duire ton trac<\/h4>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong>\u2013 et devenir une artiste confiante et expressive qui s\u2019approprie la sc\u00e8ne.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Je me d\u00e9finis comme danseuse orientale, mais depuis plus de 30 ans, j'explore un large \u00e9ventail de styles de danse et de genres musicaux issus de diff\u00e9rentes traditions du monde entier, acqu\u00e9rant ainsi une compr\u00e9hension profonde et compl\u00e8te du rythme et du mouvement.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":2714,\"width\":\"337px\",\"height\":\"auto\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"right\"} -->\n<figure class=\"wp-block-image alignright size-large is-resized\"><img src=\"https:\/\/eszter-maura.eu\/wp-content\/uploads\/2025\/07\/L1008108-618x1024.jpg\" alt=\"\" class=\"wp-image-2714\" style=\"width:337px;height:auto\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Outre mes 25 ans d'exp\u00e9rience en Raqs Sharqi (danse orientale), qui est devenue ma langue maternelle en danse, je me suis form\u00e9e \u00e0 de nombreuses danses traditionnelles et sociales du monde entier, telles que la salsa, les danses afro-colombiennes, les danses d'Afrique de l'Ouest, les danses folkloriques hongroises et d'Europe occidentale, les danses du sud de l'Italie, l'improvisation contact et le flamenco, entre autres.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Je continue d'apprendre et de m'\u00e9merveiller devant la beaut\u00e9 et l'interconnexion des diff\u00e9rentes traditions musicales et dansantes.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Je poss\u00e8de \u00e9galement plus de dix ans de formation en musique classique occidentale et une connaissance approfondie des musiques traditionnelles de nombreuses r\u00e9gions, avec un int\u00e9r\u00eat particulier pour les musiques arabe et \u00e9gyptienne.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Dans une vie ant\u00e9rieure, j'\u00e9tais architecte\/ing\u00e9nieure et j'ai acquis les comp\u00e9tences n\u00e9cessaires pour d\u00e9composer et expliquer en d\u00e9tail les concepts li\u00e9s \u00e0 la danse ou \u00e0 la musique aux danseuses d'un esprit analytique.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>J'ai aussi \u00e9t\u00e9 traductrice, ce qui, combin\u00e9 \u00e0 mon exp\u00e9rience dans divers styles de danse et de musique, m'a permis de d\u00e9velopper une compr\u00e9hension des liens entre les cultures, particuli\u00e8rement pr\u00e9cieuse pour les danseuses qui ne sont pas issues des cultures fondatrices du Raqs Sharqi.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":2370,\"width\":\"451px\",\"height\":\"auto\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"left\"} -->\n<figure class=\"wp-block-image alignleft size-large is-resized\"><img src=\"https:\/\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD-1024x683.jpeg\" alt=\"\" class=\"wp-image-2370\" style=\"width:451px;height:auto\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Ma soif d'aventure m'a men\u00e9e \u00e0 un p\u00e9riple de 8&nbsp;000&nbsp;km \u00e0 v\u00e9lo le long des c\u00f4tes d'Europe occidentale et m\u00e9ridionale, de Bruxelles \u00e0 Cadix puis \u00e0 G\u00eanes, en vivant sous une tente pendant pr\u00e8s d'un an. Ce voyage m'a aussi appris \u00e0 tracer mon propre chemin, sans me soucier des attentes de la soci\u00e9t\u00e9 \u2013&nbsp;une femme grosse, d'un certain \u00e2ge, avec des maladies chroniques&nbsp;\u2013, afin de t'aider \u00e0 acqu\u00e9rir les connaissances, le pragmatisme et la confiance en toi n\u00e9cessaires pour t'approprier ton corps et ton parcours cr\u00e9atif, quel que soit ton  niveau en danse.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":2823,\"width\":\"338px\",\"height\":\"auto\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"right\"} -->\n<figure class=\"wp-block-image alignright size-large is-resized\"><img src=\"https:\/\/eszter-maura.eu\/wp-content\/uploads\/2026\/03\/fbsize-3954-684x1024.jpg\" alt=\"\" class=\"wp-image-2823\" style=\"width:338px;height:auto\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Je crois que la danse est et devrait \u00eatre \u00ab&nbsp;la musique rendue visible&nbsp;\u00bb, et je m\u2019appuie sur la musique pour guider mes cr\u00e9ations. Je crois que la musicalit\u00e9 est primordiale pour tout danseur&nbsp;; et que c\u2019est une comp\u00e9tence qui peut s\u2019acqu\u00e9rir et se d\u00e9velopper \u00e0 tout \u00e2ge et \u00e0 tout niveau. Je crois qu\u2019il est possible de se connecter \u00e0 la musique et \u00e0 la danse \u00e9gyptiennes \u00e0 travers sa propre exp\u00e9rience culturelle, et de cr\u00e9er des danses inspir\u00e9es de sa propre vision artistique, dans le plus grand respect des cultures d\u2019origine.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Je crois que la danse, port\u00e9e par la musique, permet d\u2019acc\u00e9der \u00e0 ses v\u00e9rit\u00e9s les plus profondes&nbsp;; que nous avons tous en nous la capacit\u00e9 d\u2019explorer ces profondeurs et de cr\u00e9er un art qui nous relie \u00e0 nous-m\u00eames et touche les autres.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Je crois qu\u2019\u00e0 travers l\u2019art de la danse, on apprend \u00e0 s\u2019approprier son corps, \u00e0 s\u2019y sentir bien et \u00e0 y trouver de la joie&nbsp;; et qu\u2019en cr\u00e9ant un tel art, on devient un vecteur de beaut\u00e9, ind\u00e9pendamment de son apparence ou de son estime de soi.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Je suis l\u00e0 pour t'aider \u00e0 te r\u00e9approprier ton corps et \u00e0 t'y sentir bien, \u00e0 y trouver du plaisir et \u00e0 oser prendre ta place, par la danse ; et pour t'aider \u00e0 donner du sens \u00e0 toutes les facettes de tes connaissances en danse gr\u00e2ce \u00e0 une compr\u00e9hension et une connexion profondes avec la musique.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u2013 afin que tu puisse commencer \u00e0 cr\u00e9er des danses qui touchent l'\u00e2me de ton public.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:buttons {\"layout\":{\"type\":\"flex\",\"justifyContent\":\"center\"}} -->\n<div class=\"wp-block-buttons\"><!-- wp:button {\"textColor\":\"white\",\"width\":100,\"className\":\"is-style-fill\",\"style\":{\"color\":{\"background\":\"#77041b\"},\"elements\":{\"link\":{\"color\":{\"text\":\"var:preset|color|white\"}}}}} -->\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100 is-style-fill\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" style=\"background-color:#77041b\"><strong>Contacte-moi<\/strong><\/a><\/div>\n<!-- \/wp:button --><\/div>\n<!-- \/wp:buttons -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->"},"excerpt":{"rendered":"","protected":false,"raw":""},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_en_post_content":"<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Hi, I'm Eszter-Maura.<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>I\u2019m a dancer, writer (and part-time nomad), here to to help you own and feel at home in your body, to find delight in it and dare to take up space, though dance; and to help you develop your musicality so that you can&nbsp;rely on your music to support you as a solid foundation for your dance,&nbsp;establish a cultural connection by embodying the music,&nbsp;reduce your stage fright<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>I call myself a belly dancer - but for the last 30 years (and more), I\u2019ve explored a wide range of dance styles and music genres from different traditions all over the world, acquiring a deep and comprehensive understanding of rhythm and movement in the process.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":2714,\"width\":\"337px\",\"height\":\"auto\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"right\"} -->\n<figure class=\"wp-block-image alignright size-large is-resized\"><img src=\"https:\/\/eszter-maura.eu\/wp-content\/uploads\/2025\/07\/L1008108-618x1024.jpg\" alt=\"\" class=\"wp-image-2714\" style=\"width:337px;height:auto\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>On top of 25 years of experience in Raqs Sharqi \/ belly dance \u2013 which has become my mother tongue of dance \u2013 I\u2019ve trained in a number of traditional and social dances from over the world, such as salsa, Afro-Colombian dances, West-African-dances, Hungarian folk, Western-European folk, South-Italian dances, contact improvisation and flamenco, among others.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>I keep learning and marvelling at the beauty and interconnectedness of different musical and dance traditions.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u200bI also have over a decade\u2019s worth training in Western classical music and extensive knowledge of traditional music from many different regions, with a special focus on Arabic and Egyptian music.\u00a0<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>In a past life, I was an architect\/engineer, and gained the skills to break down and explain concepts related to dance or music in detail to the dancer with an analytical mind.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u200b<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>I used to be a translator, which, along with my experience in a variety of dance and musical styles, gave me insights into connecting to different cultures, which is especially helpful for dancers not from the source cultures of Raqs Sharqi.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":2370,\"width\":\"451px\",\"height\":\"auto\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"left\"} -->\n<figure class=\"wp-block-image alignleft size-large is-resized\"><img src=\"https:\/\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD-1024x683.jpeg\" alt=\"\" class=\"wp-image-2370\" style=\"width:451px;height:auto\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>My thirst for adventure led me on a 8000 km cycle trip along the coasts of Western and Southern Europe, from Brussels to C\u00e1diz and to Genoa, living in a tent for nearly a year. It also made me learn to create my own path, regardless of what society expects from me \u2013 a fat, middle-aged, chronically ill woman \u2013,\u00a0 so I can help you gain the knowledge, the pragmatism and the self-confidence to take ownership of your body and your creative path, no matter your level of dance technique.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":2823,\"width\":\"338px\",\"height\":\"auto\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"right\"} -->\n<figure class=\"wp-block-image alignright size-large is-resized\"><img src=\"https:\/\/eszter-maura.eu\/wp-content\/uploads\/2026\/03\/fbsize-3954-684x1024.jpg\" alt=\"\" class=\"wp-image-2823\" style=\"width:338px;height:auto\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>I believe that dance is and should be \u201cmusic made visible\u201d, and rely on the music to guide me in my creations. I believe that musicality is of utmost importance for any dancer; and that it is a skillset that you can learn and develop at any age or level. I believe that you can connect to Egyptian music and dance through your own cultural experience, and create dances based on your own artistic vision, in full respect of source cultures.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u200b<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>I believe that you can access your deepest truths through dance, with the help of the music; that we all have it in us to access those depths and create art connecting to ourselves, and touching others in the process.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u200b<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>I believe that through the art of dance, you can learn to take ownership and feel at home in your body, and find delight in it; and that by creating such art, you becomes a vessel of beauty \u2013 no matter how you look or whether you think you\u2019re pretty or not.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>I\u2019m here to to help you take ownership of and feel at home in your body, to find delight in it and dare to take up space, through dance; and to help you click into place all the unconnected bits of your dance knowledge through a deep understanding of and connection to the music<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u2013 so that you can start creating dances to touch the very souls of your audience.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:buttons {\"layout\":{\"type\":\"flex\",\"justifyContent\":\"center\"}} -->\n<div class=\"wp-block-buttons\"><!-- wp:button {\"textColor\":\"white\",\"width\":100,\"className\":\"is-style-fill\",\"style\":{\"color\":{\"background\":\"#77041b\"},\"elements\":{\"link\":{\"color\":{\"text\":\"var:preset|color|white\"}}}}} -->\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100 is-style-fill\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" style=\"background-color:#77041b\"><strong>Contact<\/strong> <strong>me<\/strong><\/a><\/div>\n<!-- \/wp:button --><\/div>\n<!-- \/wp:buttons -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->","_en_post_name":"about","_en_post_excerpt":"","_en_post_title":"About","_fr_post_content":"<!-- wp:heading {\"level\":4} -->\n<h4 class=\"wp-block-heading\">Je suis danseuse, \u00e9crivaine (et nomade \u00e0 temps partiel), et je suis l\u00e0 pour t'aider \u00e0 te sentir pleinement toi-m\u00eame dans ton corps, \u00e0 y trouver du plaisir et \u00e0 oser prendre ta place, par la danse\u00a0; et pour d\u00e9mystifier la musicalit\u00e9 afin que tu puisse t'appuyer sur ta musique comme un socle solide pour ta danse, \u00e9tablir un lien culturel en incarnant la musique, r\u00e9duire ton trac<\/h4>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong>\u2013 et devenir une artiste confiante et expressive qui s\u2019approprie la sc\u00e8ne.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Je me d\u00e9finis comme danseuse orientale, mais depuis plus de 30 ans, j'explore un large \u00e9ventail de styles de danse et de genres musicaux issus de diff\u00e9rentes traditions du monde entier, acqu\u00e9rant ainsi une compr\u00e9hension profonde et compl\u00e8te du rythme et du mouvement.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":2714,\"width\":\"337px\",\"height\":\"auto\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"right\"} -->\n<figure class=\"wp-block-image alignright size-large is-resized\"><img src=\"https:\/\/eszter-maura.eu\/wp-content\/uploads\/2025\/07\/L1008108-618x1024.jpg\" alt=\"\" class=\"wp-image-2714\" style=\"width:337px;height:auto\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Outre mes 25 ans d'exp\u00e9rience en Raqs Sharqi (danse orientale), qui est devenue ma langue maternelle en danse, je me suis form\u00e9e \u00e0 de nombreuses danses traditionnelles et sociales du monde entier, telles que la salsa, les danses afro-colombiennes, les danses d'Afrique de l'Ouest, les danses folkloriques hongroises et d'Europe occidentale, les danses du sud de l'Italie, l'improvisation contact et le flamenco, entre autres.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Je continue d'apprendre et de m'\u00e9merveiller devant la beaut\u00e9 et l'interconnexion des diff\u00e9rentes traditions musicales et dansantes.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Je poss\u00e8de \u00e9galement plus de dix ans de formation en musique classique occidentale et une connaissance approfondie des musiques traditionnelles de nombreuses r\u00e9gions, avec un int\u00e9r\u00eat particulier pour les musiques arabe et \u00e9gyptienne.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Dans une vie ant\u00e9rieure, j'\u00e9tais architecte\/ing\u00e9nieure et j'ai acquis les comp\u00e9tences n\u00e9cessaires pour d\u00e9composer et expliquer en d\u00e9tail les concepts li\u00e9s \u00e0 la danse ou \u00e0 la musique aux danseuses d'un esprit analytique.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>J'ai aussi \u00e9t\u00e9 traductrice, ce qui, combin\u00e9 \u00e0 mon exp\u00e9rience dans divers styles de danse et de musique, m'a permis de d\u00e9velopper une compr\u00e9hension des liens entre les cultures, particuli\u00e8rement pr\u00e9cieuse pour les danseuses qui ne sont pas issues des cultures fondatrices du Raqs Sharqi.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":2370,\"width\":\"451px\",\"height\":\"auto\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"left\"} -->\n<figure class=\"wp-block-image alignleft size-large is-resized\"><img src=\"https:\/\/eszter-maura.eu\/wp-content\/uploads\/2022\/06\/F306B80C-A5D6-4126-9191-94A995F6BFDD-1024x683.jpeg\" alt=\"\" class=\"wp-image-2370\" style=\"width:451px;height:auto\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Ma soif d'aventure m'a men\u00e9e \u00e0 un p\u00e9riple de 8&nbsp;000&nbsp;km \u00e0 v\u00e9lo le long des c\u00f4tes d'Europe occidentale et m\u00e9ridionale, de Bruxelles \u00e0 Cadix puis \u00e0 G\u00eanes, en vivant sous une tente pendant pr\u00e8s d'un an. Ce voyage m'a aussi appris \u00e0 tracer mon propre chemin, sans me soucier des attentes de la soci\u00e9t\u00e9 \u2013&nbsp;une femme grosse, d'un certain \u00e2ge, avec des maladies chroniques&nbsp;\u2013, afin de t'aider \u00e0 acqu\u00e9rir les connaissances, le pragmatisme et la confiance en toi n\u00e9cessaires pour t'approprier ton corps et ton parcours cr\u00e9atif, quel que soit ton  niveau en danse.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":2823,\"width\":\"338px\",\"height\":\"auto\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"right\"} -->\n<figure class=\"wp-block-image alignright size-large is-resized\"><img src=\"https:\/\/eszter-maura.eu\/wp-content\/uploads\/2026\/03\/fbsize-3954-684x1024.jpg\" alt=\"\" class=\"wp-image-2823\" style=\"width:338px;height:auto\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Je crois que la danse est et devrait \u00eatre \u00ab&nbsp;la musique rendue visible&nbsp;\u00bb, et je m\u2019appuie sur la musique pour guider mes cr\u00e9ations. Je crois que la musicalit\u00e9 est primordiale pour tout danseur&nbsp;; et que c\u2019est une comp\u00e9tence qui peut s\u2019acqu\u00e9rir et se d\u00e9velopper \u00e0 tout \u00e2ge et \u00e0 tout niveau. Je crois qu\u2019il est possible de se connecter \u00e0 la musique et \u00e0 la danse \u00e9gyptiennes \u00e0 travers sa propre exp\u00e9rience culturelle, et de cr\u00e9er des danses inspir\u00e9es de sa propre vision artistique, dans le plus grand respect des cultures d\u2019origine.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Je crois que la danse, port\u00e9e par la musique, permet d\u2019acc\u00e9der \u00e0 ses v\u00e9rit\u00e9s les plus profondes&nbsp;; que nous avons tous en nous la capacit\u00e9 d\u2019explorer ces profondeurs et de cr\u00e9er un art qui nous relie \u00e0 nous-m\u00eames et touche les autres.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Je crois qu\u2019\u00e0 travers l\u2019art de la danse, on apprend \u00e0 s\u2019approprier son corps, \u00e0 s\u2019y sentir bien et \u00e0 y trouver de la joie&nbsp;; et qu\u2019en cr\u00e9ant un tel art, on devient un vecteur de beaut\u00e9, ind\u00e9pendamment de son apparence ou de son estime de soi.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Je suis l\u00e0 pour t'aider \u00e0 te r\u00e9approprier ton corps et \u00e0 t'y sentir bien, \u00e0 y trouver du plaisir et \u00e0 oser prendre ta place, par la danse ; et pour t'aider \u00e0 donner du sens \u00e0 toutes les facettes de tes connaissances en danse gr\u00e2ce \u00e0 une compr\u00e9hension et une connexion profondes avec la musique.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u2013 afin que tu puisse commencer \u00e0 cr\u00e9er des danses qui touchent l'\u00e2me de ton public.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:buttons {\"layout\":{\"type\":\"flex\",\"justifyContent\":\"center\"}} -->\n<div class=\"wp-block-buttons\"><!-- wp:button {\"textColor\":\"white\",\"width\":100,\"className\":\"is-style-fill\",\"style\":{\"color\":{\"background\":\"#77041b\"},\"elements\":{\"link\":{\"color\":{\"text\":\"var:preset|color|white\"}}}}} -->\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100 is-style-fill\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" style=\"background-color:#77041b\"><strong>Contacte-moi<\/strong><\/a><\/div>\n<!-- \/wp:button --><\/div>\n<!-- \/wp:buttons -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->","_fr_post_name":"","_fr_post_excerpt":"","_fr_post_title":"\u00a0\u00c0 propos","_nl_post_content":"","_nl_post_name":"","_nl_post_excerpt":"","_nl_post_title":"","edit_language":"fr","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"class_list":["post-2701","page","type-page","status-publish","hentry","post"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/P4KP79-Hz","jetpack_likes_enabled":false,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eszter-maura.eu\/fr\/wp-json\/wp\/v2\/pages\/2701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eszter-maura.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eszter-maura.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eszter-maura.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eszter-maura.eu\/fr\/wp-json\/wp\/v2\/comments?post=2701"}],"version-history":[{"count":10,"href":"https:\/\/eszter-maura.eu\/fr\/wp-json\/wp\/v2\/pages\/2701\/revisions"}],"predecessor-version":[{"id":2852,"href":"https:\/\/eszter-maura.eu\/fr\/wp-json\/wp\/v2\/pages\/2701\/revisions\/2852"}],"wp:attachment":[{"href":"https:\/\/eszter-maura.eu\/fr\/wp-json\/wp\/v2\/media?parent=2701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}